{"id":5649448,"date":"2019-04-02T13:23:46","date_gmt":"2019-04-02T13:23:46","guid":{"rendered":"https:\/\/www.herreradelduque.com\/?p=5649448"},"modified":"2019-04-02T13:23:46","modified_gmt":"2019-04-02T13:23:46","slug":"estreno-de-dolor-y-gloria","status":"publish","type":"post","link":"https:\/\/www.herreradelduque.com\/en\/estreno-de-dolor-y-gloria\/","title":{"rendered":"Estreno de &#8216;Dolor y gloria&#8217;"},"content":{"rendered":"<p>Estreno de la \u00faltima pel\u00edcula de Pedro Almod\u00f3var. <!--more--><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Lugar<\/strong>: Palacio de la Cultura<\/li>\n<li><strong>Horario sesiones<\/strong>: domingo 7 y lunes 8 de abril a las 21:00 horas.<\/li>\n<li><strong>Sinopsis<\/strong>: Salvador Mallo es un aclamado director de cine en su ocaso. Su memoria le llevar\u00e1 hasta su infancia en el pueblo valenciano de Paterna en los a\u00f1os 60 junto a sus padres, a sus primeros amores, su primer deseo, la madre, la mortalidad, su primer amor adulto ya en el Madrid de los 80, el dolor de la ruptura de este amor cuando todav\u00eda estaba vivo y palpitante, la escritura como \u00fanica terapia para olvidar lo inolvidable, el temprano descubrimiento del cine y el vac\u00edo, el inconmensurable vac\u00edo ante la imposibilidad de seguir rodando.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Estreno de la &uacute;ltima pel&iacute;cula de Pedro Almod&oacute;var.<\/p>\n","protected":false},"author":1,"featured_media":5649449,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/www.herreradelduque.com\/en\/wp-json\/wp\/v2\/posts\/5649448"}],"collection":[{"href":"https:\/\/www.herreradelduque.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.herreradelduque.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.herreradelduque.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.herreradelduque.com\/en\/wp-json\/wp\/v2\/comments?post=5649448"}],"version-history":[{"count":1,"href":"https:\/\/www.herreradelduque.com\/en\/wp-json\/wp\/v2\/posts\/5649448\/revisions"}],"predecessor-version":[{"id":5649450,"href":"https:\/\/www.herreradelduque.com\/en\/wp-json\/wp\/v2\/posts\/5649448\/revisions\/5649450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.herreradelduque.com\/en\/wp-json\/wp\/v2\/media\/5649449"}],"wp:attachment":[{"href":"https:\/\/www.herreradelduque.com\/en\/wp-json\/wp\/v2\/media?parent=5649448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.herreradelduque.com\/en\/wp-json\/wp\/v2\/categories?post=5649448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.herreradelduque.com\/en\/wp-json\/wp\/v2\/tags?post=5649448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}